{"id":14,"date":"2017-09-08T16:58:18","date_gmt":"2017-09-08T14:58:18","guid":{"rendered":"https:\/\/www.suroflex.de\/?page_id=14"},"modified":"2023-04-05T09:36:56","modified_gmt":"2023-04-05T07:36:56","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/www.suroflex.de\/de_DE\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"<h4><span style=\"font-family: arial, helvetica, sans-serif;\">1. Datenschutz auf einen Blick<\/span><\/h4>\n<p><strong><span style=\"font-family: arial, helvetica, sans-serif;\">Allgemeine Hinweise<\/span><\/strong><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie unsere Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen.\u00a0Definitionen verwendeter Begriffe finden Sie im Artikel 4 der DS-GVO. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung.<\/span><\/p>\n<h4><span style=\"font-family: arial, helvetica, sans-serif;\">Datenerfassung auf unserer Website<\/span><\/h4>\n<p><strong><span style=\"font-family: arial, helvetica, sans-serif;\">Wer ist verantwortlich f\u00fcr die Datenerfassung auf dieser Website?<\/span><\/strong><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Die Datenverarbeitung auf dieser Website erfolgt durch die Suroflex GmbH, Eisenh\u00e4mmerstr. 9 in 92237 Sulzbach-Rosenberg.<br \/>\n<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>Wie erfassen wir Ihre Daten?<\/strong><\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Ihre Daten werden zum einen dadurch erhoben, dass Sie uns diese mitteilen. Hierbei handelt es sich neben Kontaktdaten um Inhaltsdaten, die Sie uns mit der E-Mail \u00fcbermitteln.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Nutzungs-, Kommunikations-, und Metadaten werden automatisch beim Besuch der Website durch unsere IT-Systeme erfasst. Das sind vor allem technische Daten (z.B. IP-Adresse, Internetbrowser, Betriebssystem oder Uhrzeit des Seitenaufrufs). Die Erfassung dieser Daten erfolgt automatisch, sobald Sie unsere Website betreten.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>Wof\u00fcr nutzen wir Ihre Daten?<\/strong><\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Ein Teil der Daten wird erhoben, um eine fehlerfreie Bereitstellung der Website zu gew\u00e4hrleisten. Andere Daten k\u00f6nnen zur Analyse Ihres Nutzerverhaltens verwendet werden.<\/span><\/p>\n<p><strong><span style=\"font-family: arial, helvetica, sans-serif;\">Welche Rechte haben Sie bez\u00fcglich Ihrer Daten?<\/span><\/strong><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Sie haben jederzeit das Recht unentgeltlich Auskunft \u00fcber Herkunft, Empf\u00e4nger und Zweck Ihrer gespeicherten personenbezogenen Daten zu erhalten. Sie haben au\u00dferdem ein Recht, die Berichtigung, Sperrung oder L\u00f6schung dieser Daten zu verlangen. Hierzu sowie zu weiteren Fragen zum Thema Datenschutz k\u00f6nnen Sie sich jederzeit unter der im Impressum angegebenen Adresse an uns wenden. Des Weiteren steht Ihnen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Au\u00dferdem haben Sie das Recht, unter bestimmten Umst\u00e4nden die Einschr\u00e4nkung der Verarbeitung Ihrer <\/span><span style=\"font-family: arial, helvetica, sans-serif;\">personenbezogenen Daten zu verlangen. Details hierzu entnehmen Sie dieser Datenschutzerkl\u00e4rung unter <\/span><span style=\"font-family: arial, helvetica, sans-serif;\">\u201eRecht auf Einschr\u00e4nkung der Verarbeitung\u201c.<\/span><\/p>\n<h4><span style=\"font-family: arial, helvetica, sans-serif;\">2. Allgemeine Hinweise und Pflichtinformationen<\/span><\/h4>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>Datenschutz<\/strong><\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Personenbezogenen Daten behandeln wir vertraulich, entsprechend gesetzlicher Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Wenn Sie diese Website benutzen, werden verschiedene personenbezogene Daten erhoben. Personenbezogene Daten sind Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Die vorliegende Datenschutzerkl\u00e4rung erl\u00e4utert, welche Daten wir erheben und wof\u00fcr wir sie nutzen. Sie erl\u00e4utert auch, wie und zu welchem Zweck das geschieht.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z.B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<\/span><\/p>\n<p><strong><span style=\"font-family: arial, helvetica, sans-serif;\">Hinweis zur verantwortlichen Stelle<\/span><\/strong><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Die verantwortliche Stelle f\u00fcr die Verarbeitung personenbezogener Daten auf diesen Internetseiten ist:<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Suroflex GmbH<\/span><br \/>\n<span style=\"font-family: arial, helvetica, sans-serif;\"> Eisenh\u00e4mmerstr. 9<\/span><br \/>\n<span style=\"font-family: arial, helvetica, sans-serif;\"> 92237 Sulzbach-Rosenberg<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Telefon: +49 9661 904-0<br \/>\nE-Mail: &#x69;&#x6e;&#x66;&#x6f;&#x40;&#115;&#117;&#114;&#111;fle&#x78;&#x2e;&#x64;&#x65;<br \/>\n<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">E-Mail Datenschutzbeauftragter: <a href=\"&#x6d;&#97;i&#x6c;&#x74;&#111;:&#x64;&#x61;&#116;e&#x6e;&#115;c&#x68;&#x75;&#116;z&#x40;&#x73;&#117;r&#x6f;&#102;&#108;&#x65;&#x78;&#46;d&#x65;\" target=\"_blank\" rel=\"noopener\"><span style=\"font-family: arial, helvetica, sans-serif;\">datensch&#117;&#116;&#122;&#64;&#115;&#117;&#114;&#111;&#102;&#108;&#x65;&#x78;&#x2e;&#x64;&#x65;<\/span><\/a><\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Verantwortliche Stelle ist die nat\u00fcrliche oder juristische Person, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung personenbezogener Daten (z.B. Namen, E-Mail-Adressen o. \u00c4.) entscheidet.<\/span><\/p>\n<h4><span style=\"font-family: arial, helvetica, sans-serif;\">Widerruf Ihrer Einwilligung zur Datenverarbeitung<\/span><\/h4>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Viele Datenverarbeitungsvorg\u00e4nge sind nur mit Ihrer ausdr\u00fccklichen Einwilligung m\u00f6glich. Sie k\u00f6nnen eine bereits erteilte Einwilligung jederzeit widerrufen. Dazu reicht eine formlose Mitteilung per E-Mail an uns. Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitung bleibt vom Widerruf unber\u00fchrt.<\/span><\/p>\n<h4><span style=\"font-family: arial, helvetica, sans-serif;\">Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde<\/span><\/h4>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Im Falle datenschutzrechtlicher Verst\u00f6\u00dfe steht Betroffenen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu:<\/span><\/p>\n<p><strong>Besucheranschrift:<\/strong><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Bayerisches Landesamt f\u00fcr Datenschutzaufsicht (BayLDA)<\/span><br \/>\n<span style=\"font-family: arial, helvetica, sans-serif;\">Promenade 18<\/span><br \/>\n<span style=\"font-family: arial, helvetica, sans-serif;\">91522 Ansbach<\/span><\/p>\n<p><strong>Postanschrift:<\/strong><\/p>\n<p>Bayerisches Landesamt f\u00fcr Datenschutzaufsicht (BayLDA)<br \/>\nPostfach 1349<br \/>\n91504 Ansbach<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Telefon: +49 981 &#8211; 180 093-0<br \/>\n<\/span><span style=\"font-family: arial, helvetica, sans-serif;\">Telefax: <\/span><span style=\"font-family: arial, helvetica, sans-serif;\">+49 981 &#8211; 180 093-800<br \/>\n<\/span><span style=\"font-family: arial, helvetica, sans-serif;\">E-Mail: <a href=\"&#x6d;a&#x69;&#108;&#x74;&#x6f;:&#x70;&#111;&#x73;&#x74;s&#x74;&#101;&#x6c;&#x6c;e&#x40;&#108;&#x64;&#x61;&#46;&#x62;&#97;&#x79;&#x65;r&#x6e;&#46;&#x64;&#x65;\" target=\"_blank\" rel=\"noopener\">&#112;o&#x73;t&#x73;&#116;&#x65;&#108;&#x6c;&#101;&#64;&#x6c;d&#x61;&#46;&#x62;&#97;&#x79;&#101;&#x72;&#110;&#46;&#x64;e<\/a><\/span><\/p>\n<h4><span style=\"font-family: arial, helvetica, sans-serif;\">Recht auf Daten\u00fcbertragbarkeit<\/span><\/h4>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Sie haben das Recht, Daten, die wir auf Grundlage Ihrer Einwilligung oder in Erf\u00fcllung eines Vertrags automatisiert verarbeiten, an sich oder an einen Dritten in einem g\u00e4ngigen, maschinenlesbaren Format aush\u00e4ndigen zu lassen. Sofern Sie die direkte \u00dcbertragung der Daten an einen anderen Verantwortlichen verlangen, erfolgt dies nur, soweit es technisch machbar ist.<\/span><\/p>\n<h4><span style=\"font-family: arial, helvetica, sans-serif;\">SSL- bzw. TLS-Verschl\u00fcsselung<\/span><\/h4>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Diese Seite nutzt aus Sicherheitsgr\u00fcnden und zum Schutz der \u00dcbertragung vertraulicher Inhalte, wie zum Beispiel Bestellungen oder Anfragen, die Sie an uns als Seitenbetreiber senden, eine SSL-bzw. TLS-Verschl\u00fcsselung. Eine verschl\u00fcsselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von \u201chttp:\/\/\u201d auf \u201chttps:\/\/\u201d wechselt und an dem Schloss-Symbol in Ihrer Browserzeile.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Wenn die SSL- bzw. TLS-Verschl\u00fcsselung aktiviert ist, k\u00f6nnen Daten, die Sie an uns \u00fcbermitteln, nicht von Dritten mitgelesen werden.<\/span><\/p>\n<h4><span style=\"font-family: arial, helvetica, sans-serif;\">Auskunft, Sperrung, L\u00f6schung<\/span><\/h4>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Sie haben im Rahmen der geltenden gesetzlichen Bestimmungen jederzeit das Recht auf unentgeltliche Auskunft \u00fcber Ihre gespeicherten personenbezogenen Daten, deren Herkunft und Empf\u00e4nger und den Zweck der Datenverarbeitung und ggf. ein Recht auf Berichtigung, Sperrung oder L\u00f6schung dieser Daten. Hierzu sowie zu weiteren Fragen zum Thema personenbezogene Daten k\u00f6nnen Sie sich jederzeit unter der im Impressum angegebenen Adresse an uns wenden.<\/span><\/p>\n<h4><span style=\"font-family: arial, helvetica, sans-serif;\">Recht auf Einschr\u00e4nkung der Verarbeitung<\/span><\/h4>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Sie haben das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. <\/span><span style=\"font-family: arial, helvetica, sans-serif;\">Hierzu k\u00f6nnen Sie sich jederzeit unter der im Impressum angegebenen Adresse an uns wenden. Das Recht<\/span> <span style=\"font-family: arial, helvetica, sans-serif;\">auf Einschr\u00e4nkung der Verarbeitung besteht in folgenden F\u00e4llen:<\/span><\/p>\n<ul>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">Wenn Sie die Richtigkeit Ihrer bei uns gespeicherten personenbezogenen Daten bestreiten, ben\u00f6tigen wir <\/span><span style=\"font-family: arial, helvetica, sans-serif;\">in der Regel Zeit, um dies zu \u00fcberpr\u00fcfen. F\u00fcr die Dauer der Pr\u00fcfung haben Sie das Recht, die<\/span> <span style=\"font-family: arial, helvetica, sans-serif;\">Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">Wenn die Verarbeitung Ihrer personenbezogenen Daten unrechtm\u00e4\u00dfig geschah \/ geschieht, k\u00f6nnen Sie <\/span><span style=\"font-family: arial, helvetica, sans-serif;\">statt der L\u00f6schung die Einschr\u00e4nkung der Datenverarbeitung verlangen.<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">Wenn wir Ihre personenbezogenen Daten nicht mehr ben\u00f6tigen, Sie sie jedoch zur Aus\u00fcbung, <\/span><span style=\"font-family: arial, helvetica, sans-serif;\">Verteidigung oder Geltendmachung von Rechtsanspr\u00fcchen ben\u00f6tigen, haben Sie das Recht, statt der<\/span> <span style=\"font-family: arial, helvetica, sans-serif;\">L\u00f6schung die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">Wenn Sie einen Widerspruch nach Art. 21 Abs. 1 DSGVO eingelegt haben, muss eine Abw\u00e4gung zwischen <\/span><span style=\"font-family: arial, helvetica, sans-serif;\">Ihren und unseren Interessen vorgenommen werden. Solange noch nicht feststeht, wessen Interessen<\/span> <span style=\"font-family: arial, helvetica, sans-serif;\">\u00fcberwiegen, haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten <\/span><span style=\"font-family: arial, helvetica, sans-serif;\">zu verlangen.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Wenn Sie die Verarbeitung Ihrer personenbezogenen Daten eingeschr\u00e4nkt haben, d\u00fcrfen diese Daten \u2013 von <\/span><span style=\"font-family: arial, helvetica, sans-serif;\">ihrer Speicherung abgesehen \u2013 nur mit Ihrer Einwilligung oder zur Geltendmachung, Aus\u00fcbung oder<\/span> <span style=\"font-family: arial, helvetica, sans-serif;\">Verteidigung von Rechtsanspr\u00fcchen oder zum Schutz der Rechte einer anderen nat\u00fcrlichen oder <\/span><span style=\"font-family: arial, helvetica, sans-serif;\">juristischen Person oder aus Gr\u00fcnden eines wichtigen \u00f6ffentlichen Interesses der Europ\u00e4ischen Union oder <\/span><span style=\"font-family: arial, helvetica, sans-serif;\">eines Mitgliedstaats verarbeitet werden.<\/span><\/p>\n<h4><span style=\"font-family: arial, helvetica, sans-serif;\">3. Datenschutzbeauftragter<\/span><\/h4>\n<p><strong><span style=\"font-family: arial, helvetica, sans-serif;\">Gesetzlich vorgeschriebener Datenschutzbeauftragter<\/span><\/strong><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Wir haben f\u00fcr unser Unternehmen einen Datenschutzbeauftragten bestellt:<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Suroflex GmbH<\/span><br \/>\n<span style=\"font-family: arial, helvetica, sans-serif;\"> Datenschutz<\/span><br \/>\n<span style=\"font-family: arial, helvetica, sans-serif;\"> Eisenh\u00e4mmertsr. 9<\/span><br \/>\n<span style=\"font-family: arial, helvetica, sans-serif;\"> 92237 Sulzbach-Rosenberg<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Telefon: +49 9661 904-157<\/span><br \/>\n<span style=\"font-family: arial, helvetica, sans-serif;\"> E-Mail: <a href=\"&#109;&#x61;&#x69;l&#116;&#x6f;:&#100;&#x61;t&#101;&#x6e;s&#99;&#x68;&#x75;&#116;&#x7a;&#x40;s&#117;&#x72;o&#102;&#x6c;e&#120;&#x2e;&#x64;&#101;\" target=\"_blank\" rel=\"noopener\">&#100;&#x61;&#116;&#x65;&#110;&#x73;&#99;&#x68;u&#x74;z&#x40;s&#x75;r&#111;&#x66;&#108;&#x65;&#120;&#x2e;&#100;&#x65;<\/a><\/span><\/p>\n<h4><span style=\"font-family: arial, helvetica, sans-serif;\">4. Datenerfassung auf unserer Website<\/span><\/h4>\n<p><strong><span style=\"font-family: arial, helvetica, sans-serif;\">Cookies<\/span><\/strong><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Die Internetseiten verwenden teilweise so genannte Cookies. Cookies richten auf Ihrem Rechner keinen Schaden an und enthalten keine Viren. Cookies dienen dazu, unser Angebot nutzerfreundlicher, effektiver und sicherer zu machen. Cookies sind kleine Textdateien, die auf Ihrem Rechner abgelegt werden und die Ihr Browser speichert.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Die meisten der von uns verwendeten Cookies sind so genannte \u201cSession-Cookies\u201d. Sie werden nach Ende Ihres Besuchs automatisch gel\u00f6scht. Andere Cookies bleiben auf Ihrem Endger\u00e4t gespeichert bis Sie diese l\u00f6schen. Diese Cookies erm\u00f6glichen es der Website, Ihren Browser beim n\u00e4chsten Besuch wiederzuerkennen.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen sowie das automatische L\u00f6schen der Cookies beim Schlie\u00dfen des Browser aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t von Websites eingeschr\u00e4nkt sein. Exemplarisch <\/span><span style=\"font-family: arial, helvetica, sans-serif;\">ein paar Anleitungen zur Deaktvierung von Cookies:<\/span><\/p>\n<ul>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">Edge: Men\u00fc &#8222;Einstellung > Erweiterte Einstellungen anzeigen&#8220;, dort unter dem Men\u00fcpunkt &#8222;Cookies&#8220; &#8222;Alle Cookies blockieren&#8220; ausw\u00e4hlen\u00a0<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">Firefox: <a title=\"Firefox Cookies deaktivieren\" href=\"https:\/\/support.mozilla.org\/de\/kb\/Cookies-blockieren\" target=\"_blank\" rel=\"noopener\">https:\/\/support.mozilla.org\/de\/kb\/Cookies-blockieren<\/a><\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">Internet Explorer: <a title=\"Internet Explorer Cookies verwalten\" href=\"https:\/\/support.microsoft.com\/de-de\/help\/17442\/windows-internet-explorer-delete-manage-cookies\" target=\"_blank\" rel=\"noopener\">https:\/\/support.microsoft.com\/de-de\/help\/17442\/windows-internet-explorer-delete-manage-cookies<\/a><\/span><\/li>\n<\/ul>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Cookies, die zur Durchf\u00fchrung des elektronischen Kommunikationsvorgangs oder zur Bereitstellung bestimmter, von Ihnen erw\u00fcnschter Funktionen (z.B. Sprachauswahl) erforderlich sind, werden auf Grundlage von Art. 6 Abs. 1 lit. f DS-GVO gespeichert. Wir haben ein berechtigtes Interesse an der Speicherung von Cookies zur technisch fehlerfreien und optimierten Bereitstellung der Website sowie der besucherbezogenen Steuerung der Websitenutzung (z. B. Sprachauswahl).<\/span><\/p>\n<h4><span style=\"font-family: arial, helvetica, sans-serif;\">Server-Log-Dateien<\/span><\/h4>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Der Provider der Seiten erhebt und speichert automatisch Informationen in so genannten Server-Log-Dateien, die Ihr Browser automatisch an uns \u00fcbermittelt. Dies sind:<\/span><\/p>\n<ul>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">Browsertyp und Browserversion<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">verwendetes Betriebssystem<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">Referrer URL<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">Hostname des zugreifenden Rechners<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">Uhrzeit der Serveranfrage<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">IP-Adresse<\/span><\/li>\n<\/ul>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Eine Zusammenf\u00fchrung dieser Daten mit anderen Datenquellen wird nicht vorgenommen.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Grundlage f\u00fcr die Datenverarbeitung ist Art. 6 Abs. 1 lit. f DS-GVO, Wir haben ein berechtigtes Interesse an der technisch fehlerfreien Darstellung und der Optimierung unserer Website \u2013 hierzu m\u00fcssen die Server-Log-Files erfasst werden.<br \/>\n<\/span><\/p>\n<h4><span style=\"font-family: arial, helvetica, sans-serif;\">Kontaktaufnahme<\/span><\/h4>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Wenn Sie uns per E-Mail Anfragen zukommen lassen, werden Ihre Angaben inklusive der von Ihnen dort angegebenen Kontaktdaten zwecks Bearbeitung der Anfrage und f\u00fcr den Fall von Anschlussfragen bei uns gespeichert. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Die Verarbeitung der \u00fcbermittelten Daten erfolgt somit ausschlie\u00dflich auf Grundlage Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DS-GVO). Sie k\u00f6nnen diese Einwilligung jederzeit widerrufen. Dazu reicht eine formlose Mitteilung per <a title=\"Erfassung, Speicherung und Nutzung personenbezogener Daten\" href=\"&#x6d;&#x61;&#105;&#108;t&#x6f;&#x3a;&#x64;&#97;&#116;e&#x6e;&#x73;&#x63;&#104;&#117;t&#x7a;&#x40;&#x73;&#117;&#114;o&#x66;&#x6c;&#x65;&#120;&#46;d&#x65;\" target=\"_blank\" rel=\"noopener\">E-Mail<\/a> an uns. Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitungsvorg\u00e4nge bleibt vom Widerruf unber\u00fchrt.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Von Ihnen bei Kontaktaufnahme \u00fcbermittelte Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z.B. nach abgeschlossener Bearbeitung Ihrer Anfrage). Zwingende gesetzliche Bestimmungen \u2013 insbesondere Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/span><\/p>\n<h4><span style=\"font-family: arial, helvetica, sans-serif;\">5. Datenerfassung und -verarbeitung im Rahmen einer Gesch\u00e4ftsbeziehung:<\/span><\/h4>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Im Rahmen einer Gesch\u00e4ftsbeziehung speichern wir zur ordnungsgem\u00e4\u00dfen Gesch\u00e4ftsabwicklung notwendige Daten unserer Gesch\u00e4ftspartner, wie z. B. Anschrift, Telefon- und Telefaxnummern, Steuernummern und im Verlauf der gesch\u00e4ftlichen Beziehung anfallende Daten wie Anfragen, Angebote, Auftr\u00e4ge, Bankverbindungen, Bestellungen, Lieferscheine, Rechnungen, usw.. <\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Von Kontaktpersonen unserer Gesch\u00e4ftspartner erfassen wir personenbezogene Daten wie Namen, zugeh\u00f6rige, ggf. personalisierte Unternehmens-E-Mailadressen und Position im Unternehmen, soweit es zur ordnungsgem\u00e4\u00dfen Anbahnung, Begr\u00fcndung und Durchf\u00fchrung eines Vertragsverh\u00e4ltnisses notwendig ist. Diese Daten werden von uns im Einklang mit den Regelungen der Datenschutz-Grundverordnung und des Bundesdatenschutzgesetzes erhoben, gespeichert und verarbeitet, die Speicherdauer richtet sich nach <\/span><\/p>\n<ul>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">dem Durchf\u00fchrungszeitraum des Vertragsverh\u00e4ltnisses und\u00a0 <\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">gesetzlichen Anforderungen an Aufbewahrungsfristen. <\/span><\/li>\n<\/ul>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Eine Weitergabe personenbezogener Daten an Lieferanten, Dienstleister oder Kunden erfolgt, wenn sich die Notwendigkeit dazu zur Begr\u00fcndung und Durchf\u00fchrung eines Vertragsverh\u00e4ltnisses ergibt.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Gem\u00e4\u00df Artikel 15 DS-GVO sind Sie berechtigt, die Suroflex GmbH um umfangreiche Auskunft zu den zu Ihrem Unternehmen gespeicherten Daten zu ersuchen.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Gem\u00e4\u00df der Artikel 16 und 17 DS-GVO k\u00f6nnen Sie von der Suroflex GmbH die Berichtigung, Vervollst\u00e4ndigung, Sperrung oder, soweit sie nicht zur Vertragserf\u00fcllung oder Verarbeitung notwendig sind, die L\u00f6schung einzelner oder aller ihrer personenbezogener Daten verlangen.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Dar\u00fcber hinaus k\u00f6nnen Sie nach Artikel 21 DS-GVO von ihrem Widerspruchsrecht Gebrauch machen und ggf. eine Einwilligungserkl\u00e4rung mit Wirkung f\u00fcr die Zukunft ab\u00e4ndern oder g\u00e4nzlich widerrufen. Dieser Widerruf kann postalisch, per <a title=\"Erfassung, Speicherung &#038; Nutzung personenbezogener Datenfrage \" href=\"&#109;&#x61;&#105;&#x6c;&#116;&#x6f;&#58;&#x64;&#97;&#x74;&#101;&#x6e;&#115;&#x63;&#104;&#x75;&#116;&#x7a;&#64;&#x73;&#117;&#x72;&#111;&#x66;&#108;&#x65;x&#x2e;d&#x65;\" target=\"_blank\" rel=\"noopener\">E-Mail<\/a> oder per Fax (0 96 61 &#8211; 904-222) an die Suroflex GmbH \u00fcbermittelt werden.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>6. Bewerbungen<\/strong><\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Wir bieten Ihnen die M\u00f6glichkeit, sich bei uns z. B. per E-Mail oder per Brief zu bewerben. Im Folgenden informieren wir Sie \u00fcber Umfang, Zweck und Verwendung Ihrer im Rahmen des Bewerbungsprozesses erhobenen personenbezogenen Daten. Wir versichern, dass Erhebung, Verarbeitung und Nutzung Ihrer Daten in \u00dcbereinstimmung mit geltendem Datenschutzrecht und allen weiteren gesetzlichen Bestimmungen erfolgt und Ihre Daten streng vertraulich behandelt werden.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>Umfang und Zweck der Datenerhebung<\/strong><\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Wenn Sie uns eine Bewerbung zukommen lassen, verarbeiten wir Ihre damit verbundenen personenbezogenen Daten (z. B. Kontakt- und Kommunikationsdaten, \u00a0Bewerbungsunterlagen, Notizen im Rahmen von Bewerbungsgespr\u00e4chen etc.), soweit dies zur Entscheidung \u00fcber die Begr\u00fcndung eines Besch\u00e4ftigungsverh\u00e4ltnisses erforderlich ist. Rechtsgrundlage hierf\u00fcr ist \u00a7 26 BDSG nach deutschem Recht (Anbahnung eines Besch\u00e4ftigungsverh\u00e4ltnisses), Art. 6 Abs. 1 lit. b DS-GVO (allgemeine Vertragsanbahnung) und \u2013 sofern Sie eine Einwilligung erteilt haben \u2013 Art. 6 Abs. 1 lit. a DS-GVO. Die Einwilligung ist jederzeit widerrufbar. Ihre personenbezogenen Daten werden innerhalb unseres Unternehmens ausschlie\u00dflich an Personen weitergegeben, die an der Bearbeitung Ihrer Bewerbung beteiligt sind.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Sofern die Bewerbung erfolgreich ist, werden die von Ihnen \u00fcbermittelten Daten auf Grundlage von \u00a7 26 BDSG und Art. 6 Abs. 1 lit. b DS-GVO zum Zwecke der Durchf\u00fchrung des Besch\u00e4ftigungsverh\u00e4ltnisses in unseren Datenverarbeitungssystemen gespeichert.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>Aufbewahrungsdauer der Daten<\/strong><\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Wenn wir Ihnen kein Stellenangebot machen k\u00f6nnen, Sie ein Stellenangebot ablehnen, Ihre Bewerbung zur\u00fcckziehen, Ihre Einwilligung zur Datenverarbeitung widerrufen oder uns zur L\u00f6schung der Daten auffordern, werden von Ihnen \u00fcbermittelte Daten inkl. ggf. verbleibender physischer Bewerbungsunterlagen f\u00fcr maximal 6 Monate nach Abschluss des Bewerbungsverfahrens gespeichert bzw. aufbewahrt (Aufbewahrungsfrist), um Einzelheiten des Bewerbungsprozesses im Falle von Unstimmigkeiten nachvollziehen zu k\u00f6nnen (Art. 6 Abs. 1 lit. f DS-GVO).<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Dieser Speicherung k\u00f6nnen Sie widersprechen, sofern Ihrerseits unsere Interessen \u00fcberwiegende berechtigte Interessen vorliegen.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Nach Ablauf der Aufbewahrungsfrist werden die Daten gel\u00f6scht, sofern keine gesetzliche Aufbewahrungspflicht oder ein sonstiger Rechtsgrund zur weiteren Speicherung vorliegt. Sofern ersichtlich ist, dass die Aufbewahrung Ihrer Daten nach Ablauf der Aufbewahrungsfrist erforderlich sein wird (z. B. aufgrund eines drohenden oder anh\u00e4ngigen Rechtsstreits), findet eine L\u00f6schung erst statt, wenn die Daten gegenstandslos geworden sind. Sonstige gesetzliche Aufbewahrungspflichten bleiben unber\u00fchrt.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><em>Quelle: <a href=\"https:\/\/www.e-recht24.de\">e-recht24.de<\/a>, vom Webseitenbetreiber modifiziert.<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<h4><span style=\"font-family: arial, helvetica, sans-serif;\">1. Datenschutz auf einen Blick<\/span><\/h4>\n<p><strong><span style=\"font-family: arial, helvetica, sans-serif;\">Allgemeine Hinweise<\/span><\/strong><\/p>\n<p><span style=\"font-family: arial, ...\n<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-14","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.suroflex.de\/de_DE\/wp-json\/wp\/v2\/pages\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.suroflex.de\/de_DE\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.suroflex.de\/de_DE\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.suroflex.de\/de_DE\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suroflex.de\/de_DE\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":120,"href":"https:\/\/www.suroflex.de\/de_DE\/wp-json\/wp\/v2\/pages\/14\/revisions"}],"predecessor-version":[{"id":1320,"href":"https:\/\/www.suroflex.de\/de_DE\/wp-json\/wp\/v2\/pages\/14\/revisions\/1320"}],"wp:attachment":[{"href":"https:\/\/www.suroflex.de\/de_DE\/wp-json\/wp\/v2\/media?parent=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}